{"id":13087,"date":"2023-01-27T17:56:34","date_gmt":"2023-01-27T20:56:34","guid":{"rendered":"https:\/\/jornalcorporativo.com.br\/?p=13087"},"modified":"2023-01-27T17:56:39","modified_gmt":"2023-01-27T20:56:39","slug":"juro-medio-dos-bancos-sobe-82-pontos-em-2022-mais-que-a-alta-da-selic","status":"publish","type":"post","link":"https:\/\/jornalcorporativo.com.br\/en\/economia\/juro-medio-dos-bancos-sobe-82-pontos-em-2022-mais-que-a-alta-da-selic\/","title":{"rendered":"Juro m\u00e9dio dos bancos sobe 8,2 pontos em 2022, mais que a alta da Selic"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A taxa m\u00e9dia de juros cobrada pelos bancos em suas opera\u00e7\u00f5es com pessoas f\u00edsicas e com empresas registrou alta de 8,2 pontos percentuais no ano de 2022 e chegou a 42% ao ano em dezembro. A informa\u00e7\u00e3o foi divulgada nesta sexta-feira (27) pelo Banco Central.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O juro m\u00e9dio, nesse caso, foi calculado com base em recursos livres \u2013 ou seja, n\u00e3o inclui os setores habitacional, rural e o Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o BC, a taxa m\u00e9dia de juros cobrada nas opera\u00e7\u00f5es com empresas subiu de 19,7% ao ano, em dezembro de 2021, para 23,1% ao ano no fim do ano passado. O aumento foi de 3,4 pontos percentuais.<br>J\u00e1 nas opera\u00e7\u00f5es com pessoas f\u00edsicas, os juros subiram de 45% ao ano, em dezembro de 2021, para 55,8% ao ano no fechamento do \u00faltimo ano. A alta foi de 10,8 pontos percentuais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alta do juro b\u00e1sico<br>Com o aumento registrado no ano passado, os juros banc\u00e1rios m\u00e9dios subiram mais do que a taxa b\u00e1sica da economia, a Selic, que avan\u00e7ou 4,5 pontos percentuais (de 9,25% para 13,75% ao ano) no mesmo per\u00edodo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O objetivo do ciclo da alta da taxa Selic, segundo o BC, foi conter as press\u00f5es inflacion\u00e1rias decorrentes da pandemia da Covid, a alta dos pre\u00e7os dos combust\u00edveis e dos alimentos (reflexo da guerra na Ucr\u00e2nia).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cheque especial e cart\u00e3o de cr\u00e9dito<br>No cheque especial das pessoas f\u00edsicas, a taxa recuou de 127,9% ao ano, em dezembro de 2021, para 131,9% ao ano no fechamento do ano passado. O aumento foi de 4 pontos percentuais em 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A taxa m\u00e9dia de juros cobrada pelos bancos nas opera\u00e7\u00f5es com cart\u00e3o de cr\u00e9dito rotativo, por sua vez, avan\u00e7ou de de 347,4% ao ano no fim de 2021 para 409,3% ao ano em dezembro do ano passado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O crescimento do juro do cart\u00e3o de cr\u00e9dito rotativo foi de 61,9 pontos percentuais em 2022 e a taxa terminou o ano no maior patamar desde agosto de 2017 (428% ao ano). A s\u00e9rie hist\u00f3rica do BC come\u00e7a em mar\u00e7o de 2011.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O cr\u00e9dito rotativo do cart\u00e3o de cr\u00e9dito pode ser acionado por quem n\u00e3o pode pagar o valor total da fatura na data do vencimento, mas n\u00e3o quer ficar inadimplente.<br>Mesmo com a queda em setembro, o patamar da taxa rotativa de juros segue proibitivo. Essa \u00e9 a linha de cr\u00e9dito mais cara do mercado e, segundo analistas, deve ser evitada. A recomenda\u00e7\u00e3o \u00e9 que os clientes banc\u00e1rios paguem todo o valor da fatura mensalmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cr\u00e9dito banc\u00e1rio<br>O volume total do cr\u00e9dito banc\u00e1rio em mercado, segundo o Banco Central, avan\u00e7ou 14% em 2022, para R$ 5,32 trilh\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apesar do aumento, houve desacelera\u00e7\u00e3o na compara\u00e7\u00e3o com o ano de 2021, quando foi registrada uma expans\u00e3o de 16,3% (valor ajustado).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O cr\u00e9dito a empresas cresceu 9,3% em 2022, na compara\u00e7\u00e3o com um aumento maior, de 10,5%, no ano anterior. J\u00e1 o cr\u00e9dito \u00e0s fam\u00edlias cresceu 17,4% no \u00faltimo ano, ap\u00f3s um aumento de 21% em 2021.<\/p>","protected":false},"excerpt":{"rendered":"<p>Juro do cart\u00e3o de cr\u00e9dito subiu mais de 60 pontos percentuais em 2022 e terminou acima de 400%<\/p>","protected":false},"author":3,"featured_media":13088,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAow6MXMDA:productID":"","footnotes":""},"categories":[4],"tags":[],"class_list":["post-13087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"brizy_media":[],"_links":{"self":[{"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/posts\/13087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/comments?post=13087"}],"version-history":[{"count":0,"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/posts\/13087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/media\/13088"}],"wp:attachment":[{"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/media?parent=13087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/categories?post=13087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/tags?post=13087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}