{"id":13095,"date":"2023-01-27T17:58:50","date_gmt":"2023-01-27T20:58:50","guid":{"rendered":"https:\/\/jornalcorporativo.com.br\/?p=13095"},"modified":"2024-01-04T12:44:22","modified_gmt":"2024-01-04T15:44:22","slug":"lula-e-governadores-divulgam-carta-em-defesa-da-democracia-valor-inegociavel","status":"publish","type":"post","link":"https:\/\/jornalcorporativo.com.br\/en\/brasil\/lula-e-governadores-divulgam-carta-em-defesa-da-democracia-valor-inegociavel\/","title":{"rendered":"Lula e governadores divulgam carta em defesa da democracia: &#8216;Valor inegoci\u00e1vel&#8217;"},"content":{"rendered":"<p class=\"wp-block-paragraph\">O presidente Luiz In\u00e1cio Lula da Silva (PT) e os governadores das 27 unidades federativas do Brasil divulgaram nesta sexta-feira (27) uma carta em defesa da democracia \u2013 que classificam como um &#8220;valor inegoci\u00e1vel&#8221;.<br>O documento foi divulgado pelo Pal\u00e1cio do Planalto ap\u00f3s reuni\u00e3o de Lula com os 27 governadores do pa\u00eds, na sede do Poder Executivo. Ministros tamb\u00e9m participaram do encontro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os governantes tamb\u00e9m dizem ter um &#8220;compromisso&#8221; com a estabilidade institucional e social do pa\u00eds. A carta foi publicada 19 dias ap\u00f3s atos golpistas promovidos por bolsonaristas radicais em Bras\u00edlia.<br>No dia 8 de janeiro, apoiadores do ex-presidente Jair Bolsonaro (PL) invadiram e vandalizaram o Pal\u00e1cio do Planalto, o Congresso Nacional e o Supremo Tribunal Federal (STF), sedes dos Tr\u00eas Poderes na capital.<br>&#8220;A democracia \u00e9 um valor inegoci\u00e1vel. Somente por meio do di\u00e1logo que ela favorece poderemos priorizar um crescimento econ\u00f4mico com redu\u00e7\u00e3o das nossas desigualdades e das mazelas sociais que hoje imp\u00f5em sofrimento e desesperan\u00e7a para uma parcela significativa da popula\u00e7\u00e3o brasileira&#8221;, diz trecho da carta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Batizado de &#8220;Carta de Bras\u00edlia&#8221;, o documento tamb\u00e9m anuncia a cria\u00e7\u00e3o do Conselho da Federa\u00e7\u00e3o, um colegiado que ser\u00e1 composto por representantes da Uni\u00e3o, dos estados e dos munic\u00edpios.<br>O objetivo do colegiado, segundo a carta, \u00e9 &#8220;definir uma agenda permanente de di\u00e1logo e pactua\u00e7\u00e3o em torno de temas definidos como priorit\u00e1rios pelos entes federados&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pe\u00e7a tamb\u00e9m fala em &#8220;gest\u00e3o compartilhada&#8221; de recursos p\u00fablicos para a\u00e7\u00f5es de desenvolvimento regional. E cita desemprego, infla\u00e7\u00e3o, fome e pobreza como problemas a serem superados pelos governos federal, estaduais e municipais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mudan\u00e7a de leis<br>O ministro da Justi\u00e7a, Fl\u00e1vio Dino, entregou ao presidente Lula propostas de mudan\u00e7a de leis para prevenir atos golpistas. Entre elas:<br>a cria\u00e7\u00e3o de uma Guarda Nacional para proteger a Esplanada dos Minist\u00e9rios em lugar da PM do Distrito Federal<br>aumentar as penas para quem participar de atos golpistas<br>acelerar a perda de bens de golpistas determinadas pela Justi\u00e7a<br>responsabilizar empresas financiadoras de atos contra a democracia<br>criar mecanismos para obrigar as plataformas de internet a serem mais rigorosas no combate a mensagens com amea\u00e7as \u00e0 democracia; conte\u00fado antidemocr\u00e1tico teria que ser exclu\u00eddo em quest\u00e3o de horas<\/p>","protected":false},"excerpt":{"rendered":"<p>O presidente Luiz In\u00e1cio Lula da Silva (PT) e os governadores das 27 unidades federativas do Brasil divulgaram nesta sexta-feira (27) uma carta em defesa da democracia \u2013 que classificam como um &#8220;valor inegoci\u00e1vel&#8221;.O documento foi divulgado pelo Pal\u00e1cio do Planalto ap\u00f3s reuni\u00e3o de Lula com os 27 governadores do pa\u00eds, na sede do Poder [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAow6MXMDA:productID":"","footnotes":""},"categories":[36],"tags":[],"class_list":["post-13095","post","type-post","status-publish","format-standard","hentry","category-brasil"],"brizy_media":[],"_links":{"self":[{"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/posts\/13095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/comments?post=13095"}],"version-history":[{"count":0,"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/posts\/13095\/revisions"}],"wp:attachment":[{"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/media?parent=13095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/categories?post=13095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/tags?post=13095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}