{"id":21529,"date":"2024-12-18T02:16:02","date_gmt":"2024-12-18T05:16:02","guid":{"rendered":"https:\/\/jornalcorporativo.com.br\/?p=21529"},"modified":"2024-12-18T02:16:02","modified_gmt":"2024-12-18T05:16:02","slug":"sp-aprova-em-2a-votacao-projeto-para-privatizar-ciclovias-centros-esportivos-e-outros-equipamentos","status":"publish","type":"post","link":"https:\/\/jornalcorporativo.com.br\/en\/brasil\/sp-aprova-em-2a-votacao-projeto-para-privatizar-ciclovias-centros-esportivos-e-outros-equipamentos\/","title":{"rendered":"SP aprova, em 2\u00aa vota\u00e7\u00e3o, projeto para privatizar ciclovias, centros esportivos e outros equipamentos"},"content":{"rendered":"<p>A C\u00e2mara Municipal de S\u00e3o Paulo aprovou, em segunda vota\u00e7\u00e3o, o projeto de lei que prev\u00ea a privatiza\u00e7\u00e3o de equipamentos p\u00fablicos na cidade como ciclovias, ciclofaixas e centros esportivos. Foram 35 votos a favor e 15 contr\u00e1rios \u00e0 proposta de autoria do prefeito Ricardo Nunes (MDB), al\u00e9m de uma absten\u00e7\u00e3o. A sess\u00e3o ocorreu na tarde desta ter\u00e7a-feira (17).<br \/>\nO PL segue agora para san\u00e7\u00e3o ou veto do pr\u00f3prio prefeito.<\/p>\n<p>O vereador Celso Gianazzi (PSOL), da oposi\u00e7\u00e3o, disse que a aprova\u00e7\u00e3o \u00e9 um &#8220;cheque em branco para as empresas privatizarem tudo&#8221;.<br \/>\nCris Monteiro (Novo) afirmou que o projeto de lei aprovado \u00e9 uma autoriza\u00e7\u00e3o para a prefeitura fazer estudos de poss\u00edveis concess\u00f5es de \u00e1reas p\u00fablicas por meio da Secretaria Executiva de Desestatiza\u00e7\u00e3o e Parcerias. &#8220;O projeto \u00e9 uma autoriza\u00e7\u00e3o para que a Secretaria de Desestatiza\u00e7\u00e3o pode fazer estudos. N\u00e3o \u00e9 privatiza\u00e7\u00e3o em si&#8221;, afirmou a vereadora.<\/p>\n<p>J\u00e1 a equipe do vereador Fabio Riva (MDB) rejeitou a compara\u00e7\u00e3o do projeto a um &#8220;cheque em branco&#8221; e afirmou que &#8220;nenhuma empresa ser\u00e1 escolhida sem debate efetivo na C\u00e2mara ou nas comiss\u00f5es&#8221;.<br \/>\nAinda n\u00e3o h\u00e1, no entanto, detalhes de como essas privatiza\u00e7\u00f5es v\u00e3o funcionar.<\/p>\n<p>O texto aprovado \u00e9 uma altera\u00e7\u00e3o da lei sancionada em 2017 pelo ex-prefeito Jo\u00e3o Doria e vai depender de regulamenta\u00e7\u00e3o.<br \/>\nLocais voltados a &#8220;cria\u00e7\u00e3o ou fortalecimento de iniciativas de economia criativa e de diversidade cultural, intelectual, hist\u00f3rica, lazer ou tur\u00edstica na cidade&#8221; tamb\u00e9m podem ser concedidos \u00e0 iniciativa privada, segundo o projeto de lei.<\/p>\n<p>Em nota, a Prefeitura de S\u00e3o Paulo afirmou que, &#8220;apesar das concess\u00f5es, os espa\u00e7os continuam sendo p\u00fablicos. Antes de qualquer celebra\u00e7\u00e3o de contrato, o projeto precisa ser deliberado pelo Conselho Municipal de Desestatiza\u00e7\u00e3o e Parcerias, receber estudos de diagn\u00f3stico e viabilidade t\u00e9cnica e passar por consultas p\u00fablicas&#8221;.<\/p>\n<p>Outros projetos<br \/>\nOs vereadores de S\u00e3o Paulo tamb\u00e9m devem votar emenda \u00e0 Lei de Zoneamento que permitiria a constru\u00e7\u00e3o de pr\u00e9dios altos em Zonas Exclusivamente Residenciais (ZER), como no bairro Vila Nova Concei\u00e7\u00e3o, pr\u00f3ximo ao Parque do Ibirapuera, na Zona Sul da capital.<\/p>\n<p>Outro projeto que deve movimentar o legislativo paulistano ainda esta semana \u00e9 o 521\/2018, que altera um mapa da Lei de Zoneamento da capital e inclui uma \u00e1rea localizada na Avenida Pacaembu, na Zona Oeste, como Zona de Corredor.<\/p>","protected":false},"excerpt":{"rendered":"<p>Projeto de lei \u00e9 de autoria do Executivo e foi aprovado por 35 votos a favor contra 15 nesta ter\u00e7a (17)<\/p>","protected":false},"author":3,"featured_media":21517,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"googlesitekit_rrm_CAow6MXMDA:productID":"","footnotes":""},"categories":[36],"tags":[],"class_list":["post-21529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil"],"brizy_media":[],"_links":{"self":[{"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/posts\/21529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/comments?post=21529"}],"version-history":[{"count":1,"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/posts\/21529\/revisions"}],"predecessor-version":[{"id":21530,"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/posts\/21529\/revisions\/21530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/media\/21517"}],"wp:attachment":[{"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/media?parent=21529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/categories?post=21529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalcorporativo.com.br\/en\/wp-json\/wp\/v2\/tags?post=21529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}